{"id":3639,"date":"2024-04-06T13:25:06","date_gmt":"2024-04-06T13:25:06","guid":{"rendered":"https:\/\/bluesparkmtl.ca\/?page_id=3639"},"modified":"2024-04-06T13:43:45","modified_gmt":"2024-04-06T13:43:45","slug":"le-modele-early-start-denver","status":"publish","type":"page","link":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/","title":{"rendered":"Le mod\u00e8le Early Start Denver (ESDM)"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-style-default\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/bluesparkmtl.ca\/wp-content\/uploads\/2024\/04\/woman-teaching-kids-scaled.jpg?w=825&#038;ssl=1\" alt=\"\" class=\"wp-image-3656\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le mod\u00e8le Early Start Denver (ESDM) est une m\u00e9thode d&rsquo;intervention fond\u00e9e sur la recherche et sp\u00e9cialement con\u00e7ue pour les jeunes enfants pr\u00e9sentant des troubles du d\u00e9veloppement. En int\u00e9grant des techniques d&rsquo;analyse comportementale appliqu\u00e9e (ABA) dans des interactions ludiques, l&rsquo;ESDM offre une approche dynamique et inclusive de l&rsquo;apprentissage, adapt\u00e9e \u00e0 un large \u00e9ventail de styles et de capacit\u00e9s d&rsquo;apprentissage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette m\u00e9thode flexible peut \u00eatre mise en \u0153uvre dans diff\u00e9rents environnements, notamment dans les centres de th\u00e9rapie, \u00e0 domicile et dans les \u00e9tablissements d&rsquo;enseignement tels que les cr\u00e8ches et les \u00e9coles maternelles, ce qui garantit la coh\u00e9rence et l&rsquo;accessibilit\u00e9 de l&rsquo;aide au d\u00e9veloppement de l&rsquo;enfant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Caract\u00e9ristiques principales de l&rsquo;ESDM :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fond\u00e9 sur des donn\u00e9es probantes :<\/strong> Elle s&rsquo;appuie sur des recherches pluridisciplinaires pour \u00e9tayer son efficacit\u00e9.<\/li>\n\n\n\n<li><strong>Inclusif et adaptable :<\/strong> Convient \u00e0 divers styles et capacit\u00e9s d&rsquo;apprentissage et peut \u00eatre adapt\u00e9 pour \u00eatre utilis\u00e9 dans de multiples contextes.<\/li>\n\n\n\n<li><strong>Participation des parents :<\/strong> Encourage la participation active des parents, en leur donnant les moyens de contribuer au d\u00e9veloppement de leur enfant par le biais de jeux interactifs et d&rsquo;activit\u00e9s de routine.<\/li>\n\n\n\n<li><strong>Administration professionnelle :<\/strong> Des th\u00e9rapeutes hautement qualifi\u00e9s assurent la qualit\u00e9 et la coh\u00e9rence des services.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-jetpack-calendly calendly-style-inline\" id=\"calendly-block-1\"><\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>ESDM bas\u00e9e sur le groupe (G-ESDM) chez Blue Spark<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Blue Spark propose l&rsquo;ESDM en groupe (G-ESDM), une adaptation innovante de l&rsquo;ESDM con\u00e7ue pour les enfants \u00e2g\u00e9s de 3 \u00e0 5 ans. Ce programme met l&rsquo;accent sur le d\u00e9veloppement de comp\u00e9tences socio-\u00e9motionnelles, cognitives et linguistiques par le biais d&rsquo;interactions facilit\u00e9es avec des pairs dans un cadre de groupe structur\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En int\u00e9grant les principes de l&rsquo;ESDM avec la dimension suppl\u00e9mentaire de l&rsquo;apprentissage social, G-ESDM offre une solution compl\u00e8te d&rsquo;intervention pr\u00e9coce qui r\u00e9pond aux besoins nuanc\u00e9s des enfants n\u00e9cessitant un soutien renforc\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Points forts de G-ESDM :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Croissance socio-\u00e9motionnelle : <\/strong>Favorise la compr\u00e9hension \u00e9motionnelle et l&#8217;empathie par l&rsquo;interaction avec les pairs.<\/li>\n\n\n\n<li><strong>D\u00e9veloppement cognitif et linguistique :<\/strong> Stimule les processus cognitifs et l&rsquo;acquisition du langage dans un contexte social.<\/li>\n\n\n\n<li><strong>Apprentissage personnalis\u00e9 :<\/strong> Chaque enfant fait l&rsquo;objet d&rsquo;une \u00e9valuation personnalis\u00e9e afin d&rsquo;adapter le programme \u00e0 ses besoins sp\u00e9cifiques en mati\u00e8re de d\u00e9veloppement.<\/li>\n\n\n\n<li><strong>Un ratio \u00e9ducateur-enfants \u00e9quilibr\u00e9 :<\/strong> Nous maintenons un faible ratio (1:4) afin de garantir une attention individualis\u00e9e et des conditions d&rsquo;apprentissage optimales.<\/li>\n\n\n\n<li><strong>Supervision par un expert :<\/strong> Supervis\u00e9 par un professionnel certifi\u00e9 ESDM Advanced Workshop pour garantir le plus haut niveau de soins et de suivi des progr\u00e8s.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 l&rsquo;int\u00e9gration d&rsquo;objectifs d&rsquo;apprentissage individualis\u00e9s dans une dynamique de groupe, la G-ESDM \u00e0 Blue Spark repr\u00e9sente une approche inclusive, engageante et efficace du d\u00e9veloppement de la petite enfance. Notre \u00e9quipe de professionnels d\u00e9vou\u00e9s s&rsquo;engage \u00e0 fournir un environnement stimulant et enrichissant o\u00f9 chaque enfant peut s&rsquo;\u00e9panouir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/calendly.com\/bluesparkmontreal\">Planifiez<\/a> une consultation t\u00e9l\u00e9phonique gratuite de 30 minutes ou appelez le (514) 607-9377<\/strong> <strong>d\u00e8s maintenant !<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mod\u00e8le Early Start Denver (ESDM) est une m\u00e9thode d&rsquo;intervention fond\u00e9e sur la recherche et sp\u00e9cialement con\u00e7ue pour les jeunes enfants pr\u00e9sentant des troubles du d\u00e9veloppement. En int\u00e9grant des techniques d&rsquo;analyse comportementale appliqu\u00e9e (ABA) dans des interactions ludiques, l&rsquo;ESDM offre une approche dynamique et inclusive de l&rsquo;apprentissage, adapt\u00e9e \u00e0 un large \u00e9ventail de styles et&hellip; <a href=\"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/\" class=\"more-link\">Lire la suite <span class=\"screen-reader-text\">Le mod\u00e8le Early Start Denver (ESDM)<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3656,"parent":3348,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/full-width-page.php","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"footnotes":""},"tags":[],"class_list":["post-3639","page","type-page","status-publish","has-post-thumbnail","hentry","without-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le mod\u00e8le Early Start Denver (ESDM) - Blue Spark Developmental Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le mod\u00e8le Early Start Denver (ESDM) - Blue Spark Developmental Center\" \/>\n<meta property=\"og:description\" content=\"Le mod\u00e8le Early Start Denver (ESDM) est une m\u00e9thode d&rsquo;intervention fond\u00e9e sur la recherche et sp\u00e9cialement con\u00e7ue pour les jeunes enfants pr\u00e9sentant des troubles du d\u00e9veloppement. En int\u00e9grant des techniques d&rsquo;analyse comportementale appliqu\u00e9e (ABA) dans des interactions ludiques, l&rsquo;ESDM offre une approche dynamique et inclusive de l&rsquo;apprentissage, adapt\u00e9e \u00e0 un large \u00e9ventail de styles et&hellip; Lire la suite Le mod\u00e8le Early Start Denver (ESDM)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Spark Developmental Center\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-06T13:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluesparkmtl.ca\/wp-content\/uploads\/2024\/04\/woman-teaching-kids-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/\",\"url\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/\",\"name\":\"Le mod\u00e8le Early Start Denver (ESDM) - Blue Spark Developmental Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/bluesparkmtl.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/woman-teaching-kids-scaled.jpg?fit=%2C&ssl=1\",\"datePublished\":\"2024-04-06T13:25:06+00:00\",\"dateModified\":\"2024-04-06T13:43:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/bluesparkmtl.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/woman-teaching-kids-scaled.jpg?fit=%2C&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/bluesparkmtl.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/woman-teaching-kids-scaled.jpg?fit=%2C&ssl=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/le-modele-early-start-denver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos services\",\"item\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/nos-services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le mod\u00e8le Early Start Denver (ESDM)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/\",\"name\":\"Blue Spark Developmental Center\",\"description\":\"Etincelle Bleue Centre de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/#organization\",\"name\":\"Blue Spark Developmental Center\",\"url\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/bluesparkmtl.ca\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-bluespark-logo.png?fit=731%2C279&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/bluesparkmtl.ca\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-bluespark-logo.png?fit=731%2C279&ssl=1\",\"width\":731,\"height\":279,\"caption\":\"Blue Spark Developmental Center\"},\"image\":{\"@id\":\"https:\\\/\\\/bluesparkmtl.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le mod\u00e8le Early Start Denver (ESDM) - Blue Spark Developmental Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/","og_locale":"fr_FR","og_type":"article","og_title":"Le mod\u00e8le Early Start Denver (ESDM) - Blue Spark Developmental Center","og_description":"Le mod\u00e8le Early Start Denver (ESDM) est une m\u00e9thode d&rsquo;intervention fond\u00e9e sur la recherche et sp\u00e9cialement con\u00e7ue pour les jeunes enfants pr\u00e9sentant des troubles du d\u00e9veloppement. En int\u00e9grant des techniques d&rsquo;analyse comportementale appliqu\u00e9e (ABA) dans des interactions ludiques, l&rsquo;ESDM offre une approche dynamique et inclusive de l&rsquo;apprentissage, adapt\u00e9e \u00e0 un large \u00e9ventail de styles et&hellip; Lire la suite Le mod\u00e8le Early Start Denver (ESDM)","og_url":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/","og_site_name":"Blue Spark Developmental Center","article_modified_time":"2024-04-06T13:43:45+00:00","og_image":[{"url":"https:\/\/bluesparkmtl.ca\/wp-content\/uploads\/2024\/04\/woman-teaching-kids-scaled.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/","url":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/","name":"Le mod\u00e8le Early Start Denver (ESDM) - Blue Spark Developmental Center","isPartOf":{"@id":"https:\/\/bluesparkmtl.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/#primaryimage"},"image":{"@id":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bluesparkmtl.ca\/wp-content\/uploads\/2024\/04\/woman-teaching-kids-scaled.jpg?fit=%2C&ssl=1","datePublished":"2024-04-06T13:25:06+00:00","dateModified":"2024-04-06T13:43:45+00:00","breadcrumb":{"@id":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/#primaryimage","url":"https:\/\/i0.wp.com\/bluesparkmtl.ca\/wp-content\/uploads\/2024\/04\/woman-teaching-kids-scaled.jpg?fit=%2C&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bluesparkmtl.ca\/wp-content\/uploads\/2024\/04\/woman-teaching-kids-scaled.jpg?fit=%2C&ssl=1"},{"@type":"BreadcrumbList","@id":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/le-modele-early-start-denver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bluesparkmtl.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos services","item":"https:\/\/bluesparkmtl.ca\/fr\/nos-services\/"},{"@type":"ListItem","position":3,"name":"Le mod\u00e8le Early Start Denver (ESDM)"}]},{"@type":"WebSite","@id":"https:\/\/bluesparkmtl.ca\/fr\/#website","url":"https:\/\/bluesparkmtl.ca\/fr\/","name":"Blue Spark Developmental Center","description":"Etincelle Bleue Centre de D\u00e9veloppement","publisher":{"@id":"https:\/\/bluesparkmtl.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluesparkmtl.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bluesparkmtl.ca\/fr\/#organization","name":"Blue Spark Developmental Center","url":"https:\/\/bluesparkmtl.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bluesparkmtl.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/bluesparkmtl.ca\/wp-content\/uploads\/2022\/04\/cropped-bluespark-logo.png?fit=731%2C279&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bluesparkmtl.ca\/wp-content\/uploads\/2022\/04\/cropped-bluespark-logo.png?fit=731%2C279&ssl=1","width":731,"height":279,"caption":"Blue Spark Developmental Center"},"image":{"@id":"https:\/\/bluesparkmtl.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/pages\/3639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/comments?post=3639"}],"version-history":[{"count":5,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/pages\/3639\/revisions"}],"predecessor-version":[{"id":3658,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/pages\/3639\/revisions\/3658"}],"up":[{"embeddable":true,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/pages\/3348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/media\/3656"}],"wp:attachment":[{"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/media?parent=3639"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluesparkmtl.ca\/fr\/wp-json\/wp\/v2\/tags?post=3639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}